{"id":28809,"date":"2023-10-30T19:45:51","date_gmt":"2023-10-30T19:45:51","guid":{"rendered":"https:\/\/helpnkprod.wpenginepowered.com\/non-classifiee\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/"},"modified":"2025-04-01T15:54:36","modified_gmt":"2025-04-01T15:54:36","slug":"16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information","status":"publish","type":"post","link":"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/","title":{"rendered":"Vue d&rsquo;ensemble de la gestion des demandes d&rsquo;information"},"content":{"rendered":"<p>Dans le cadre de la <a href=\"https:\/\/www.newforma.com\/fr\/newforma-konekt\/gestion-de-contrats\/\" target=\"_blank\" rel=\"noopener noreferrer\">gestion des contrats<\/a>, la page <strong>DI<\/strong> (demandes d\u2019information) de Newforma Konekt permet aux membres de l\u2019\u00e9quipe de projet d\u2019enregistrer et de suivre efficacement les DI tout au long du processus de r\u00e9vision.<\/p>\n<p class=\"wysiwyg-text-align-center\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/16879751658893_FR_RFIs_overview.jpg\" alt=\"FR_RFIs_overview.jpg\" \/><\/p>\n<h3 id=\"h_01HA844RDVWDBVQT9EF8AKVXSY\">Flux de travail des DI re\u00e7ues<\/h3>\n<p>Le diagramme suivant pr\u00e9sente une vue d\u2019ensemble du flux de travail des DI re\u00e7ues. Il n\u2019est pas n\u00e9cessaire d\u2019utiliser toutes les \u00e9tapes du flux de travail.<\/p>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/16985943422349-FR_RFIsFR_RFIs.png\" alt=\"FR_RFIs\" \/><\/p>\n<ol>\n<li>L\u2019auteur de la DI envoie la DI \u00e0 la personne responsable de son enregistrement sur la plateforme Newforma Konekt.<\/li>\n<li>Le responsable de la DI peut enregistrer la DI directement depuis Newforma Konekt, ou \u00e0 partir d\u2019un courriel en utilisant <a href=\"\/fr\/360002819171-add-ins\/12131929581453-outlook\/14480507106957-classer-des-courriels-outlook-dans-newforma-konekt\/\">l\u2019add-in Outlook de Newforma Konekt<\/a>.<\/li>\n<li>La DI peut ensuite \u00eatre transf\u00e9r\u00e9e pour r\u00e9vision \u00e0 d\u2019autres membres de l\u2019\u00e9quipe du projet (r\u00e9viseurs).<\/li>\n<li>Le ou les r\u00e9viseurs r\u00e9pondent \u00e0 la DI. Le responsable peut \u00e9galement\u00a0soumettre une r\u00e9ponse au nom d\u2019une autre personne.<\/li>\n<li>Lorsque le responsable de la DI re\u00e7oit la r\u00e9ponse du ou des r\u00e9viseurs, il peut soumettre la r\u00e9ponse officielle \u00e0 l\u2019auteur de la DI ou simplement fermer la DI sans fournir de r\u00e9ponse.<\/li>\n<\/ol>\n<h3 id=\"h_01HA844RDVV23CXS45RCQ5AFJZ\">Matrice des fonctionnalit\u00e9s pour les DI<\/h3>\n<p>Le tableau ci-dessous fournit une liste des fonctionnalit\u00e9s disponibles pour chaque r\u00f4le de projet.<\/p>\n<table style=\"border-collapse: collapse; width: 100%; height: 175px;\" border=\"1\">\n<tbody>\n<tr style=\"height: 22px;\">\n<td class=\"wysiwyg-text-align-center\" style=\"height: 22px; width: 209.322%;\" colspan=\"6\">Fonctionnalit\u00e9s disponibles par r\u00f4le<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td style=\"width: 79.75%; height: 21px;\"><strong>Fonctionnalit\u00e9<\/strong><\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 8.28583%; height: 21px;\"><strong>Cr\u00e9ateur<\/strong><\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 1.42857%; height: 21px;\"><strong>Admin<\/strong><\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 7.28575%; height: 21px;\"><strong>\u00c9diteur<\/strong><\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 6.28574%; height: 21px;\"><strong>Lecteur<\/strong><\/td>\n<td style=\"width: 106.286%; height: 21px;\"><strong>R\u00e9viseur<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 22px;\">\n<td style=\"width: 79.75%; height: 22px;\">Voir et r\u00e9viser toutes les DI qui vous ont \u00e9t\u00e9 transf\u00e9r\u00e9es<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 8.28583%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 1.42857%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 7.28575%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 6.28574%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 106.286%; height: 22px;\">\u2714<\/td>\n<\/tr>\n<tr style=\"height: 22px;\">\n<td style=\"width: 79.75%; height: 22px;\">T\u00e9l\u00e9chager les pi\u00e8ces jointes des DI<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 8.28583%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 1.42857%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 7.28575%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 6.28574%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 106.286%; height: 22px;\">\u2714<\/td>\n<\/tr>\n<tr style=\"height: 22px;\">\n<td style=\"width: 79.75%; height: 22px;\">Voir toutes les DI d\u2019un projet<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 8.28583%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 1.42857%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 7.28575%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 6.28574%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 106.286%; height: 22px;\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 79.75%;\">Exporter les DI dans un journal<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 8.28583%;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 1.42857%;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 7.28575%;\">\u2714<\/td>\n<td style=\"width: 6.28574%;\"><\/td>\n<td style=\"width: 106.286%;\"><\/td>\n<\/tr>\n<tr style=\"height: 22px;\">\n<td style=\"width: 79.75%; height: 22px;\">Enregistrer, modifier, transf\u00e9rer, r\u00e9viser et fermer des DI<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 8.28583%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 1.42857%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 7.28575%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 6.28574%; height: 22px;\"><\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 106.286%; height: 22px;\"><\/td>\n<\/tr>\n<tr style=\"height: 22px;\">\n<td style=\"width: 79.75%; height: 22px;\">Soumettre des r\u00e9ponses officielles<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 8.28583%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 1.42857%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 7.28575%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 6.28574%; height: 22px;\"><\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 106.286%; height: 22px;\"><\/td>\n<\/tr>\n<tr style=\"height: 22px;\">\n<td style=\"width: 79.75%; height: 22px;\">Supprimer des DI<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 8.28583%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 1.42857%; height: 22px;\">\u2714<\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 7.28575%; height: 22px;\"><\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 6.28574%; height: 22px;\"><\/td>\n<td class=\"wysiwyg-text-align-center\" style=\"width: 106.286%; height: 22px;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Notez que tous les fichiers <strong>DI<\/strong> font l&rsquo;objet d&rsquo;une recherche de logiciels malveillants lorsqu&rsquo;ils sont t\u00e9l\u00e9charg\u00e9s sur Newforma Konekt. Pour plus d&rsquo;informations, veuillez vous r\u00e9f\u00e9rer \u00e0 l&rsquo;article <a href=\"https:\/\/konekt.help.newforma.com\/wp-admin\/post.php?post=228044&amp;action=edit&amp;lang=fr&amp;admin_bar=1\">Analyse maliciel pour les documents t\u00e9l\u00e9charg\u00e9s sur le monolithe<\/a>.<\/p>\n<p>Pour plus d\u2019informations sur les DI, consultez les autres articles de cette section.<\/p>\n<ul>\n<li><a href=\"\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16436526889741-enregistrer-une-di\/\">Cr\u00e9er ou enregistrer une DI<\/a><\/li>\n<li><a href=\"\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16719924545293-modifier-une-di\/\">Modifier une DI<\/a><\/li>\n<li><a href=\"\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16723580521613-transferer-une-di-pour-revision\/\">Transf\u00e9rer une DI pour r\u00e9vision<\/a><\/li>\n<li><a href=\"\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16723654046861-soumettre-une-reponse-a-une-di\/\">Soumettre une r\u00e9ponse \u00e0 une DI<\/a><\/li>\n<li><a href=\"\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16723732449293-soumettre-une-reponse-officielle-a-une-di\/\">Soumettre la r\u00e9ponse officielle \u00e0 une DI<\/a><\/li>\n<li><a href=\"\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16723713305101-fermer-une-di-manuellement\/\">Fermer une DI manuellement<\/a><\/li>\n<li><a href=\"\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16723766984973-supprimer-une-di\/\">Supprimer une DI (administrateurs seulement)<\/a><\/li>\n<li><a href=\"\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/20752311583757-exporter-le-journal-des-di\/\">Exporter le journal des DI<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de la gestion des contrats, la page DI (demandes d\u2019information) de Newforma Konekt permet aux membres de l\u2019\u00e9quipe de projet d\u2019enregistrer et de suivre efficacement les DI tout au long du processus de r\u00e9vision. Flux de travail des DI re\u00e7ues Le diagramme suivant pr\u00e9sente une vue d\u2019ensemble du flux de travail des [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_autodraft_ids":[],"_lmt_disableupdate":"","_lmt_disable":"","_sb_is_suggestion_mode":false,"_sb_show_suggestion_boards":false,"_sb_show_comment_boards":false,"_sb_suggestion_history":"","_sb_update_block_changes":"","_is_real_time_mode":false,"_realtime_collaborators":"","footnotes":"","cf_checklist_status":[]},"categories":[436],"tags":[],"class_list":["post-28809","post","type-post","status-publish","format-standard","hentry","category-14932988377613-demandes-d-information-di"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vue d&#039;ensemble de la gestion des demandes d&#039;information - Newforma Konekt Help<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vue d&#039;ensemble de la gestion des demandes d&#039;information - Newforma Konekt Help\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre de la gestion des contrats, la page DI (demandes d\u2019information) de Newforma Konekt permet aux membres de l\u2019\u00e9quipe de projet d\u2019enregistrer et de suivre efficacement les DI tout au long du processus de r\u00e9vision. Flux de travail des DI re\u00e7ues Le diagramme suivant pr\u00e9sente une vue d\u2019ensemble du flux de travail des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/\" \/>\n<meta property=\"og:site_name\" content=\"Newforma Konekt Help\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T19:45:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T15:54:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/12761946458125-di-et-revues-des-dessins\\\/14932988377613-demandes-d-information-di\\\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/12761946458125-di-et-revues-des-dessins\\\/14932988377613-demandes-d-information-di\\\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\\\/\"},\"headline\":\"Vue d&rsquo;ensemble de la gestion des demandes d&rsquo;information\",\"datePublished\":\"2023-10-30T19:45:51+00:00\",\"dateModified\":\"2025-04-01T15:54:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/12761946458125-di-et-revues-des-dessins\\\/14932988377613-demandes-d-information-di\\\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\\\/\"},\"wordCount\":413,\"articleSection\":[\"Demandes d'information (DI)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/12761946458125-di-et-revues-des-dessins\\\/14932988377613-demandes-d-information-di\\\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\\\/\",\"url\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/12761946458125-di-et-revues-des-dessins\\\/14932988377613-demandes-d-information-di\\\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\\\/\",\"name\":\"Vue d'ensemble de la gestion des demandes d'information - Newforma Konekt Help\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/#website\"},\"datePublished\":\"2023-10-30T19:45:51+00:00\",\"dateModified\":\"2025-04-01T15:54:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/12761946458125-di-et-revues-des-dessins\\\/14932988377613-demandes-d-information-di\\\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/12761946458125-di-et-revues-des-dessins\\\/14932988377613-demandes-d-information-di\\\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/12761946458125-di-et-revues-des-dessins\\\/14932988377613-demandes-d-information-di\\\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vue d&#8217;ensemble de la gestion des demandes d&#8217;information\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/\",\"name\":\"Newforma Konekt Help\",\"description\":\"Newforma Help Center\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/konekt.help.newforma.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vue d'ensemble de la gestion des demandes d'information - Newforma Konekt Help","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/","og_locale":"fr_FR","og_type":"article","og_title":"Vue d'ensemble de la gestion des demandes d'information - Newforma Konekt Help","og_description":"Dans le cadre de la gestion des contrats, la page DI (demandes d\u2019information) de Newforma Konekt permet aux membres de l\u2019\u00e9quipe de projet d\u2019enregistrer et de suivre efficacement les DI tout au long du processus de r\u00e9vision. Flux de travail des DI re\u00e7ues Le diagramme suivant pr\u00e9sente une vue d\u2019ensemble du flux de travail des [&hellip;]","og_url":"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/","og_site_name":"Newforma Konekt Help","article_published_time":"2023-10-30T19:45:51+00:00","article_modified_time":"2025-04-01T15:54:36+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/#article","isPartOf":{"@id":"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/"},"headline":"Vue d&rsquo;ensemble de la gestion des demandes d&rsquo;information","datePublished":"2023-10-30T19:45:51+00:00","dateModified":"2025-04-01T15:54:36+00:00","mainEntityOfPage":{"@id":"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/"},"wordCount":413,"articleSection":["Demandes d'information (DI)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/","url":"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/","name":"Vue d'ensemble de la gestion des demandes d'information - Newforma Konekt Help","isPartOf":{"@id":"https:\/\/konekt.help.newforma.com\/fr\/#website"},"datePublished":"2023-10-30T19:45:51+00:00","dateModified":"2025-04-01T15:54:36+00:00","breadcrumb":{"@id":"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/konekt.help.newforma.com\/fr\/12761946458125-di-et-revues-des-dessins\/14932988377613-demandes-d-information-di\/16429328909069-vue-d-ensemble-de-la-gestion-des-demandes-d-information\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/konekt.help.newforma.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Vue d&#8217;ensemble de la gestion des demandes d&#8217;information"}]},{"@type":"WebSite","@id":"https:\/\/konekt.help.newforma.com\/fr\/#website","url":"https:\/\/konekt.help.newforma.com\/fr\/","name":"Newforma Konekt Help","description":"Newforma Help Center","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/konekt.help.newforma.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/konekt.help.newforma.com\/fr\/wp-json\/wp\/v2\/posts\/28809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/konekt.help.newforma.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/konekt.help.newforma.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/konekt.help.newforma.com\/fr\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/konekt.help.newforma.com\/fr\/wp-json\/wp\/v2\/comments?post=28809"}],"version-history":[{"count":0,"href":"https:\/\/konekt.help.newforma.com\/fr\/wp-json\/wp\/v2\/posts\/28809\/revisions"}],"wp:attachment":[{"href":"https:\/\/konekt.help.newforma.com\/fr\/wp-json\/wp\/v2\/media?parent=28809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/konekt.help.newforma.com\/fr\/wp-json\/wp\/v2\/categories?post=28809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/konekt.help.newforma.com\/fr\/wp-json\/wp\/v2\/tags?post=28809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}